{"id":2243,"date":"2022-09-02T15:20:14","date_gmt":"2022-09-02T15:20:14","guid":{"rendered":"https:\/\/ssscorp.org\/reunioes-ordinarias-e-especiais-de-2019\/"},"modified":"2022-10-20T15:21:33","modified_gmt":"2022-10-20T15:21:33","slug":"reunioes-ordinarias-e-especiais-de-2019","status":"publish","type":"page","link":"https:\/\/ssscorp.org\/pt-br\/reunioes-ordinarias-e-especiais-de-2019\/","title":{"rendered":"Reuni\u00f5es Ordin\u00e1rias e Especiais de 2019"},"content":{"rendered":"\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-1138834664\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-652250039\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h3 class=\"uppercase\"><strong>2019 Reuni\u00f5es regulares e especiais<\/strong><\/h3>\n<p>Clique na data de cada Reuni\u00e3o Ordin\u00e1ria para ver a agenda dessa reuni\u00e3o.&nbsp;<\/p>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-652250039 {\n  width: 98%;\n}\n#text-box-652250039 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1138834664 {\n  padding-top: 300px;\n}\n#banner-1138834664 .bg.bg-loaded {\n  background-image: url(https:\/\/ssscorp.org\/wp-content\/uploads\/2022\/09\/Untitled-design-3-scaled-1.jpeg);\n}\n#banner-1138834664 .overlay {\n  background-color: rgba(17, 33, 82, 0.855);\n}\n#banner-1138834664 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1138834664 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\t<section class=\"section\" id=\"section_2047209351\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1509573983\">\n\n\n\t<div id=\"col-246015058\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Agendas das Reuni\u00f5es Ordin\u00e1rias de 2019<\/span><b><\/b><\/h3><\/div>\n\n<ul>\n<li>23 de janeiro de 2019 &#8211; Reuni\u00e3o Ordin\u00e1ria do SSSC<\/li>\n<li>29 de maio de 2019 &#8211; Reuni\u00e3o Ordin\u00e1ria do SSSC<\/li>\n<li>18 de setembro de 2019 &#8211; Reuni\u00e3o Ordin\u00e1ria do SSSC<\/li>\n<li>11 de dezembro de 2019 &#8211; Reuni\u00e3o Ordin\u00e1ria do SSSC\u200b<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-582519127\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >2019 Reuni\u00f5es Especiais<\/span><b><\/b><\/h3><\/div>\n\n<ul>\n<li>2 de janeiro de 2019 &#8211; Reuni\u00e3o Especial<\/li>\n<li>19 de janeiro de 2019 &#8211; Reuni\u00e3o Especial<\/li>\n<li>20 de janeiro de 2019 &#8211; Reuni\u00e3o Especial<\/li>\n<li>21 de janeiro de 2019 &#8211; Reuni\u00e3o Especial<\/li>\n<li>13 de Fevereiro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>17 de fevereiro de 2019 &#8211; Reuni\u00e3o Especial<\/li>\n<li>20 de fevereiro de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>27 de Fevereiro de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>6 de Mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>7 de Mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>12 de Mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>13 de mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>20 de Mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>21 de mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>26 de mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>27 de mar\u00e7o de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>3 de abril de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>10 de abril de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>17 de abril de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>28 de abril de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>29 de abril de 2019 &#8211; SSSC &#8211; Reuni\u00e3o Especial<\/li>\n<li>15 de maio de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>5 de junho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>26 de junho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>10 de julho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>17 de julho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>18 de julho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>23 de julho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>24 de julho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>29 de julho de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>7 de agosto de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>13 de agosto de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>14 de agosto de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>28 de agosto de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>4 de setembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>11 de setembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>18 de setembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>29 de setembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>30 de setembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>16 de outubro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>30 de outubro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>19 de novembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>20 de novembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<li>4 de dezembro de 2019 &#8211; Reuni\u00e3o Especial do SSSC<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2047209351 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_2047209351 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_2047209351 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"iawp_total_views":18,"footnotes":""},"class_list":["post-2243","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/pages\/2243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/comments?post=2243"}],"version-history":[{"count":3,"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/pages\/2243\/revisions"}],"predecessor-version":[{"id":2295,"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/pages\/2243\/revisions\/2295"}],"wp:attachment":[{"href":"https:\/\/ssscorp.org\/pt-br\/wp-json\/wp\/v2\/media?parent=2243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}